{"id":252,"count":2,"description":"Dovolenka v Eur\u00f3pe a cestovanie po Eur\u00f3pe na vlastn\u00fa p\u00e4s\u0165","link":"https:\/\/misketravels.cz\/sk\/category\/europa\/","name":"Eur\u00f3pa","slug":"europa","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/misketravels.cz\/sk\/wp-json\/wp\/v2\/categories\/252","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/misketravels.cz\/sk\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/misketravels.cz\/sk\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/misketravels.cz\/sk\/wp-json\/wp\/v2\/posts?categories=252"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}